{"id":139,"date":"2022-07-19T09:43:33","date_gmt":"2022-07-19T09:43:33","guid":{"rendered":"https:\/\/tractor-pto-shafts.top\/china-oem-tractor-pto-drive-shaft-power-take-off-agricultural-transmission-manufacturing-plant-heavy-duty-farm-steering-industries-best-telescopic-tube-cross-joints-shaft-with-hot-selling\/"},"modified":"2022-07-19T09:43:33","modified_gmt":"2022-07-19T09:43:33","slug":"china-oem-tractor-pto-drive-shaft-power-take-off-agricultural-transmission-manufacturing-plant-heavy-duty-farm-steering-industries-best-telescopic-tube-cross-joints-shaft-with-hot-selling","status":"publish","type":"post","link":"https:\/\/tractor-pto-shafts.top\/fr\/application\/arbre-de-transmission-de-prise-de-force-pour-tracteur-oem-chinois-usine-de-fabrication-de-transmissions-agricoles-direction-agricole-robuste-meilleurs-tubes-telescopiques-a-joints-croises-tres-pop\/","title":{"rendered":"Arbre de transmission de prise de force pour tracteur OEM chinois, usine de fabrication de transmissions agricoles, direction agricole robuste, meilleurs tubes t\u00e9lescopiques \u00e0 joints crois\u00e9s, tr\u00e8s populaire"},"content":{"rendered":"<p>\n<h2>Description du produit<\/h2>\n<p>\n<p><\/p>\n<p><strong>Arbre de transmission de prise de force pour tracteur, usine de fabrication de transmissions agricoles, direction agricole robuste, meilleurs tubes t\u00e9lescopiques \u00e0 joints transversaux.<\/strong><\/p>\n<p>arbre de prise de force du tracteur<\/p>\n<p>La prise de force (PDF) est un dispositif qui transmet la puissance m\u00e9canique d'un moteur \u00e0 un autre \u00e9quipement d\u00e9pourvu de moteur \u00e9lectrique. Il s'agit d'un arbre de transmission cannel\u00e9 install\u00e9 sur un tracteur permettant d'alimenter directement des outils gr\u00e2ce au moteur.<\/p>\n<p>La prise de force (PDF) est un dispositif qui transmet la puissance m\u00e9canique d'un moteur \u00e0 un autre \u00e9quipement. Elle permet \u00e0 la source d'\u00e9nergie principale de fournir de la puissance \u00e0 un \u00e9quipement suppl\u00e9mentaire d\u00e9pourvu de moteur \u00e9lectrique. Par exemple, une PDF permet d'actionner un marteau-piqueur \u00e0 l'aide du moteur d'un tracteur.<\/p>\n<p>\n<p>\n<p>\n<h2>Pourquoi il est important de v\u00e9rifier l'arbre de transmission<\/h2>\n<p>Si vous entendez des cliquetis en conduisant, votre arbre de transmission pourrait n\u00e9cessiter une r\u00e9paration. Un m\u00e9canicien exp\u00e9riment\u00e9 pourra d\u00e9terminer si le bruit provient d'un seul c\u00f4t\u00e9 ou des deux. Ce probl\u00e8me est g\u00e9n\u00e9ralement li\u00e9 au convertisseur de couple. Poursuivez votre lecture pour comprendre pourquoi il est si important de faire inspecter votre arbre de transmission par un m\u00e9canicien. Voici quelques sympt\u00f4mes \u00e0 surveiller. Les cliquetis peuvent avoir de nombreuses causes. Commencez par v\u00e9rifier si le bruit provient de l'avant ou de l'arri\u00e8re du v\u00e9hicule.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/Drive-shaft\/t-Driveshaft-1.webp\" alt=\"compresseur d&#039;air\" width=\"800\" title=\"\"><\/p>\n<h2>arbre de transmission creux<\/h2>\n<p>Les arbres de transmission creux pr\u00e9sentent de nombreux avantages. L\u00e9gers, ils contribuent \u00e0 r\u00e9duire le poids total du v\u00e9hicule. CZPT est le premier fabricant mondial de ces composants. L'entreprise propose \u00e9galement des solutions all\u00e9g\u00e9es pour diverses applications, notamment les essieux haute performance. Fabriqu\u00e9s selon une technologie de pointe, les arbres de transmission CZPT offrent une excellente qualit\u00e9 \u00e0 des prix comp\u00e9titifs.<br \/>Le diam\u00e8tre int\u00e9rieur de l'arbre creux r\u00e9duit l'amplitude des forces internes, diminuant ainsi le couple transmis. Contrairement aux arbres pleins, les arbres creux sont de plus en plus r\u00e9sistants. Le mat\u00e9riau qui les compose est l\u00e9g\u00e8rement plus l\u00e9ger, ce qui r\u00e9duit encore leur poids et le couple global. Cependant, cela augmente \u00e9galement la r\u00e9sistance \u00e0 l'\u00e9coulement \u00e0 haute vitesse. De ce fait, dans de nombreuses applications, les arbres de transmission creux sont moins performants que les arbres de transmission pleins.<br \/>Un arbre de transmission creux classique se compose d'une premi\u00e8re tige 14 et d'une seconde tige 14 de chaque c\u00f4t\u00e9. La premi\u00e8re tige est reli\u00e9e \u00e0 la seconde, cette derni\u00e8re s'\u00e9tendant dans le sens de rotation. Les deux tiges sont ensuite soud\u00e9es par friction \u00e0 la partie centrale de l'arbre creux. La chaleur g\u00e9n\u00e9r\u00e9e par la friction lors de la rotation relative assure la liaison des deux parties. Les arbres de transmission creux peuvent \u00eatre utilis\u00e9s dans les moteurs \u00e0 combustion interne et les v\u00e9hicules respectueux de l'environnement.<br \/>Le principal avantage d'un arbre de transmission creux r\u00e9side dans la r\u00e9duction de son poids. Les cannelures peuvent \u00eatre con\u00e7ues avec un diam\u00e8tre inf\u00e9rieur \u00e0 celui de l'arbre, ce qui permet une r\u00e9duction de poids significative. De plus, les arbres creux sont moins susceptibles de se bloquer que les arbres pleins. \u00c0 terme, les arbres de transmission creux devraient dominer le march\u00e9 mondial des arbres de transmission automobiles. Parmi leurs avantages, on note une consommation de carburant r\u00e9duite et une plus grande flexibilit\u00e9 par rapport aux arbres de transmission pleins.<\/p>\n<h2>Arbre de transmission Cardan<\/h2>\n<p>Les arbres de transmission \u00e0 cardan sont tr\u00e8s r\u00e9pandus dans les machines industrielles. Ils servent \u00e0 transmettre la puissance d'une machine \u00e0 une autre et sont disponibles en diff\u00e9rentes tailles et formes. Ils sont propos\u00e9s dans divers mat\u00e9riaux, notamment l'acier, le cuivre et l'aluminium. Si vous envisagez d'installer un arbre de transmission \u00e0 cardan, il est important de conna\u00eetre les diff\u00e9rents types disponibles. Pour trouver la solution la plus adapt\u00e9e, consultez notre catalogue.<br \/>Les arbres de transmission t\u00e9lescopiques ou \u00ab\u00a0\u00e0 cardan\u00a0\u00bb, \u00e9galement appel\u00e9s joints de cardan, sont id\u00e9aux pour une transmission efficace du couple entre la transmission et le syst\u00e8me de sortie. Ils sont performants, l\u00e9gers et \u00e9conomes en \u00e9nergie. Leur conception fait appel \u00e0 des m\u00e9thodes avanc\u00e9es, notamment la mod\u00e9lisation par \u00e9l\u00e9ments finis (MEF), afin d'optimiser les performances, le poids et l'efficacit\u00e9. De plus, la longueur de l'arbre \u00e0 cardan est ajustable pour faciliter son repositionnement.<br \/>Un autre choix courant pour les arbres de transmission est l'arbre de Cardan, \u00e9galement appel\u00e9 arbre de transmission. Son r\u00f4le est de transmettre le couple du moteur aux roues. On le trouve g\u00e9n\u00e9ralement dans les moteurs de voitures hautes performances. Certains mod\u00e8les sont fabriqu\u00e9s en laiton, en fonte ou en acier et pr\u00e9sentent des profils sp\u00e9cifiques. Les arbres de Cardan existent en versions inclin\u00e9es et parall\u00e8les.<br \/>Les arbres de transmission \u00e0 simple cardan sont couramment utilis\u00e9s en remplacement des arbres de transmission standard. Cependant, si vous recherchez des arbres de transmission \u00e0 double cardan pour votre v\u00e9hicule, optez pour la s\u00e9rie 1310. Ce type d'arbre est id\u00e9al pour les Jeep sur\u00e9lev\u00e9es et n\u00e9cessite une bo\u00eete de transfert compatible avec les joints homocin\u00e9tiques. Certains mod\u00e8les requi\u00e8rent m\u00eame des entretoises d'essieu. Les arbres de transmission \u00e0 double cardan sont \u00e9galement con\u00e7us pour les suspensions sur\u00e9lev\u00e9es, ce qui en fait un excellent choix pour ajuster la hauteur de caisse des Jeep.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/Drive-shaft\/c-Driveshaft-1.webp\" alt=\"compresseur d&#039;air\" width=\"800\" title=\"\"><\/p>\n<h2>joint universel<\/h2>\n<p>Les joints de cardan sont un excellent choix pour les arbres de transmission fonctionnant \u00e0 vitesse constante. Leur conception permet un rapport de vitesse angulaire constant entre les arbres d'entr\u00e9e et de sortie. Selon l'application, la limite de vitesse recommand\u00e9e peut varier en fonction de l'angle de fonctionnement, de la puissance de transmission et de l'utilisation. Ces recommandations doivent \u00eatre bas\u00e9es sur la pression. La vitesse maximale admissible de l'arbre de transmission est d\u00e9termin\u00e9e par le calcul de l'acc\u00e9l\u00e9ration angulaire.<br \/>Les joints de cardan, ne n\u00e9cessitant pas de graisse, peuvent durer longtemps, mais finissent par s'user. Un manque de lubrification ou un s\u00e9chage excessif peuvent entra\u00eener un contact m\u00e9tal sur m\u00e9tal. Il en va de m\u00eame pour les joints universels non lubrifi\u00e9s. Malgr\u00e9 leur longue dur\u00e9e de vie, il peut \u00eatre difficile de rep\u00e9rer les signes avant-coureurs d'une d\u00e9faillance. Pour \u00e9viter cela, il est conseill\u00e9 de contr\u00f4ler r\u00e9guli\u00e8rement l'arbre de transmission.<br \/>Les joints de cardan ne doivent pas d\u00e9passer 70 % de leur vitesse critique lat\u00e9rale. Au-del\u00e0 de cette limite, la pi\u00e8ce subira des vibrations inacceptables, r\u00e9duisant ainsi sa dur\u00e9e de vie. Pour d\u00e9terminer le joint de cardan le mieux adapt\u00e9 \u00e0 votre application, veuillez contacter votre fournisseur. G\u00e9n\u00e9ralement, les faibles vitesses ne n\u00e9cessitent pas d'\u00e9quilibrage. Dans ce cas, il est conseill\u00e9 d'utiliser un diam\u00e8tre primitif plus important afin de r\u00e9duire l'effort axial.<br \/>Pour minimiser la vitesse angulaire et le couple de l'arbre de sortie, les deux articulations doivent \u00eatre en phase. Par cons\u00e9quent, le d\u00e9placement angulaire de l'arbre de sortie ne suit pas parfaitement celui de l'arbre d'entr\u00e9e\u00a0; il pr\u00e9sente un d\u00e9calage, en avance ou en retard. La figure\u00a03 illustre la variation de la vitesse angulaire et l'avance de d\u00e9placement maximale du cardan. Les rapports sont indiqu\u00e9s ci-dessous. Le couple appropri\u00e9 pour cette application est de 1\u00a0360\u00a0po-lb.<\/p>\n<h2>Arbre de transmission remis \u00e0 neuf<\/h2>\n<p>Les arbres de transmission reconditionn\u00e9s pr\u00e9sentent plusieurs avantages. Moins chers que les mod\u00e8les neufs, ils sont g\u00e9n\u00e9ralement tout aussi fiables. Essentiels au fonctionnement de toute voiture, camion ou autobus, les arbres de transmission sont constitu\u00e9s de tubes m\u00e9talliques creux. Si cette conception permet de r\u00e9duire le poids et le co\u00fbt, elle les rend vuln\u00e9rables aux agressions ext\u00e9rieures. Un arbre de transmission peut alors se fissurer ou se tordre. Ce type de dommage peut causer de graves dommages \u00e0 la transmission.<br \/>L'arbre de transmission d'une voiture est un composant essentiel qui transmet le couple du moteur aux roues. A1 Drive Shaft est un fournisseur mondial d'arbres de transmission et de composants automobiles. Son usine est en mesure de remettre \u00e0 neuf et de r\u00e9parer la quasi-totalit\u00e9 des marques et mod\u00e8les d'arbres de transmission. Des arbres de transmission remis \u00e0 neuf sont disponibles pour tous les types de v\u00e9hicules. On les trouve sur le march\u00e9 pour une grande vari\u00e9t\u00e9 de v\u00e9hicules, notamment les voitures particuli\u00e8res, les camions, les fourgonnettes et les SUV.<br \/>Des bruits inhabituels indiquent que votre arbre de transmission doit \u00eatre remplac\u00e9. Des joints de cardan et des silentblocs us\u00e9s peuvent provoquer des vibrations excessives. Ces pi\u00e8ces entra\u00eenent une usure pr\u00e9matur\u00e9e d'autres \u00e9l\u00e9ments de la transmission. Si vous constatez l'un de ces sympt\u00f4mes, veuillez faire inspecter votre v\u00e9hicule au centre AAMCO de la r\u00e9gion de la baie de San Francisco. Si vous soup\u00e7onnez un dommage \u00e0 l'arbre de transmission, n'attendez pas\u00a0: cela peut s'av\u00e9rer tr\u00e8s dangereux.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/Drive-shaft\/b-Driveshaft-1.webp\" alt=\"compresseur d&#039;air\" width=\"800\" title=\"\"><\/p>\n<h2>Le co\u00fbt du remplacement de l'arbre de transmission<\/h2>\n<p>Le co\u00fbt du remplacement d'un arbre de transmission est variable, mais en moyenne, cette r\u00e9paration co\u00fbte entre 1\u00a0200 et 1\u00a0500\u00a0\u20ac. Bien que ce prix puisse varier selon le v\u00e9hicule, le co\u00fbt des pi\u00e8ces et de la main-d'\u0153uvre est g\u00e9n\u00e9ralement \u00e9quivalent. Si vous effectuez la r\u00e9paration vous-m\u00eame, il est conseill\u00e9 de vous renseigner sur le co\u00fbt des pi\u00e8ces et de la main-d'\u0153uvre avant de commencer les travaux. Certaines pi\u00e8ces peuvent \u00eatre plus ch\u00e8res que d'autres\u00a0; il est donc judicieux de comparer les prix de plusieurs garages avant de faire votre choix.<br \/>Si vous constatez l'un de ces sympt\u00f4mes, rendez-vous imm\u00e9diatement dans un garage. En cas de doute sur l'\u00e9tat de l'arbre de transmission, ne conduisez pas votre v\u00e9hicule tant qu'il n'a pas \u00e9t\u00e9 r\u00e9par\u00e9. Les sympt\u00f4mes \u00e0 surveiller incluent une perte de puissance, des difficult\u00e9s \u00e0 d\u00e9placer le v\u00e9hicule, des grincements, des cliquetis ou des vibrations en roulant.<br \/>Les pi\u00e8ces utilis\u00e9es dans les arbres de transmission comprennent les paliers centraux, les joints coulissants et les joints de cardan. Le prix d'un arbre de transmission varie selon le v\u00e9hicule et peut m\u00eame varier d'un mod\u00e8le \u00e0 l'autre au sein d'une m\u00eame ann\u00e9e. De plus, les diff\u00e9rents types d'arbres de transmission n\u00e9cessitent des m\u00e9thodes de r\u00e9paration diff\u00e9rentes et sont donc beaucoup plus co\u00fbteux. En g\u00e9n\u00e9ral, le remplacement d'un arbre de transmission co\u00fbte entre $300 et $1\u00a0300. L'op\u00e9ration peut prendre environ une heure, selon le mod\u00e8le du v\u00e9hicule.<br \/>Plusieurs facteurs peuvent n\u00e9cessiter le remplacement de l'arbre de transmission, notamment la corrosion des roulements, des joints d'\u00e9tanch\u00e9it\u00e9 endommag\u00e9s ou d'autres composants. Dans certains cas, l'\u00e9tat du joint de cardan indique que l'arbre de transmission doit \u00eatre remplac\u00e9. M\u00eame si les roulements et les joints de cardan sont en bon \u00e9tat, ils finiront par se casser et n\u00e9cessiter le remplacement de l'arbre de transmission. Cependant, ces pi\u00e8ces sont co\u00fbteuses et si un arbre de transmission endommag\u00e9 est le sympt\u00f4me d'un probl\u00e8me plus important, il est conseill\u00e9 de le remplacer.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/ptoshaft\/Ptoshaft-l1.webp\" alt=\"Arbre de transmission de prise de force pour tracteur OEM chinois, usine de fabrication de transmissions agricoles, direction agricole robuste, meilleurs tubes t\u00e9lescopiques \u00e0 joints crois\u00e9s, tr\u00e8s populaire\" title=\"\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/ptoshaft\/Ptoshaft-l2.webp\" alt=\"Arbre de transmission de prise de force pour tracteur OEM chinois, usine de fabrication de transmissions agricoles, direction agricole robuste, meilleurs tubes t\u00e9lescopiques \u00e0 joints crois\u00e9s, tr\u00e8s populaire\" title=\"\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description Tractor PTO Drive Shaft Power Take off Agricultural Transmission Manufacturing Plant Heavy-Duty Farm Steering Industries Best Telescopic Tube Cross Joints Shaft tractor pto shaft Power take-off (PTO) is a device that transfers an engine&#8217;s mechanical power to another piece of equipment which does not have its own engine or motor. Otherwise it is [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[216,78,217,81,30,31,32,163,39,218,219,220,43,46,47,221,48,49,50,222,223,51,224,53,55,56,170,225,61,62,63,65,66,67,68,69,226,227],"class_list":["post-139","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-agricultural-power","tag-agricultural-shaft","tag-agricultural-tube","tag-cross-drive-shaft","tag-drive-shaft-oem","tag-drive-shaft-pto","tag-drive-shaft-tractor","tag-farm-tractor","tag-oem-shaft","tag-power-drive-transmission","tag-power-take-off-shaft","tag-power-transmission-shaft","tag-pto-drive-shaft","tag-pto-shaft","tag-pto-shaft-drive","tag-pto-shaft-tube","tag-shaft","tag-shaft-drive","tag-shaft-pto-shaft","tag-shaft-steering","tag-shaft-telescopic","tag-shaft-tractor","tag-steering-shaft","tag-tractor","tag-tractor-china","tag-tractor-drive-shaft","tag-tractor-farm","tag-tractor-power-steering","tag-tractor-pto","tag-tractor-pto-drive-shaft","tag-tractor-pto-shaft","tag-tractor-shaft","tag-tractor-tractor-tractor","tag-tractor-tractor-tractor-tractor","tag-tractor-transmission","tag-transmission-shaft","tag-tube-shaft","tag-tube-tractor"],"_links":{"self":[{"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":0,"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"wp:attachment":[{"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tractor-pto-shafts.top\/fr\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}